{"id":35,"count":6,"description":"Retrouvez ici assortiment de fruits secs, <strong>confiseries aux amandes<\/strong>, noisettes, et graines de courge enrob\u00e9es de chocolat. Croquant, fondant, croustillant, d\u00e9licieux ! Les produits Confiserie Adam sont labellis\u00e9s Agriculture Biologique, certification qui vous garantit le meilleur. Au-del\u00e0 du Bio, les gourmandises Adam sont <strong>fabriqu\u00e9es en France<\/strong>.","link":"https:\/\/confiserie-adam.fr\/boutique\/categorie-produit\/encas-bio\/amandes-noisettes-graines\/","name":"Amandes, noisettes et graines au chocolat Bio","slug":"amandes-noisettes-graines","taxonomy":"product_cat","parent":28,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/confiserie-adam.fr\/boutique\/wp-json\/wp\/v2\/product_cat\/35"}],"collection":[{"href":"https:\/\/confiserie-adam.fr\/boutique\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/confiserie-adam.fr\/boutique\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/confiserie-adam.fr\/boutique\/wp-json\/wp\/v2\/product_cat\/28"}],"wp:post_type":[{"href":"https:\/\/confiserie-adam.fr\/boutique\/wp-json\/wp\/v2\/product?product_cat=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}